{"id":13,"count":7,"description":"","link":"https:\/\/hellogrowing.com\/blog\/category\/digital-jobs-in-india\/","name":"Digital Jobs in India","slug":"digital-jobs-in-india","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/hellogrowing.com\/blog\/wp-json\/wp\/v2\/categories\/13","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/hellogrowing.com\/blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/hellogrowing.com\/blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/hellogrowing.com\/blog\/wp-json\/wp\/v2\/posts?categories=13"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}